{"id":5,"date":"2022-11-11T17:41:30","date_gmt":"2022-11-11T17:41:30","guid":{"rendered":"https:\/\/ivyfragrance.com\/?page_id=5"},"modified":"2026-06-29T15:02:17","modified_gmt":"2026-06-29T11:02:17","slug":"home","status":"publish","type":"page","link":"https:\/\/ivyfragrance.com\/ar\/","title":{"rendered":"Home"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"5\" class=\"elementor elementor-5\">\n\t\t\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-869bdde elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"869bdde\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1f7d62e\" data-id=\"1f7d62e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<link rel=\"stylesheet\" id=\"wd-mod-animations-keyframes-css\" href=\"https:\/\/ivyfragrance.com\/wp-content\/themes\/woodmart\/css\/parts\/mod-animations-keyframes.min.css?ver=8.3.9\" type=\"text\/css\" media=\"all\" \/> \t\t\t\t\t<div class=\"elementor-element elementor-element-f420c48 animated-slow elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"f420c48\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;_animation&quot;:&quot;none&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"polite\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 2\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"f420c48\" data-elementor-lightbox-title=\"IVY banners\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6IjM2NTUiLCJ1cmwiOiJodHRwczpcL1wvaXZ5ZnJhZ3JhbmNlLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDJcL0lWWS1iYW5uZXJzLnBuZyIsInNsaWRlc2hvdyI6ImY0MjBjNDgifQ%3D%3D\" href=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/IVY-banners.png\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/IVY-banners.png\" alt=\"IVY banners\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 2\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"f420c48\" data-elementor-lightbox-title=\"IMG_1713\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6IjQxMzQiLCJ1cmwiOiJodHRwczpcL1wvaXZ5ZnJhZ3JhbmNlLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMTFcL0lNR18xNzEzLnBuZyIsInNsaWRlc2hvdyI6ImY0MjBjNDgifQ%3D%3D\" href=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/11\/IMG_1713.png\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/11\/IMG_1713.png\" alt=\"IMG_1713\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-circle-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-circle-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-5c600a2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5c600a2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3168af1\" data-id=\"3168af1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5c44a86 elementor-widget elementor-widget-heading\" data-id=\"5c44a86\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">\u0648\u0635\u0644 \u062d\u062f\u064a\u062b\u0627\u064b<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-590815d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"590815d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-63b6ef0\" data-id=\"63b6ef0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bc4f169 wd-width-100 elementor-widget elementor-widget-wd_products\" data-id=\"bc4f169\" data-element_type=\"widget\" data-widget_type=\"wd_products.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\n\t\t\t<div id=\"carousel-433\" class=\"wd-carousel-container  wd-products-element wd-products products\">\n\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t<div class=\"wd-carousel-inner\">\n\t\t\t\t\t<div class=\"wd-carousel wd-grid\" data-scroll_per_page=\"yes\" style=\"--wd-col-lg:3;--wd-col-md:3;--wd-col-sm:2;--wd-gap-lg:20px;--wd-gap-sm:10px;\">\n\t\t\t\t\t\t<div class=\"wd-carousel-wrap\">\n\t\t\t\t\t\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-icons product-grid-item product type-product post-4630 status-publish instock product_cat-perfume has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"1\" data-id=\"4630\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/ivyfragrance.com\/ar\/product\/blush-rose\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Blush Rose\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/IMG_1697-1024x1024.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/IMG_1697-1024x1024.png 1024w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/IMG_1697-300x300.png 300w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/IMG_1697-150x150.png 150w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/IMG_1697-768x768.png 768w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/IMG_1697-12x12.png 12w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/IMG_1697-400x400.png 400w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/IMG_1697-600x600.png 600w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/IMG_1697.png 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/48-1024x1024.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/48-1024x1024.png 1024w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/48-300x300.png 300w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/48-150x150.png 150w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/48-768x768.png 768w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/48-12x12.png 12w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/48-400x400.png 400w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/48-600x600.png 600w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/48.png 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"\/ar\/wp-json\/wp\/v2\/pages\/5?add-to-cart=4630\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_4630\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"4630\" data-product_sku=\"IVY-1016\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Blush Rose&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Blush Rose&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0633\u0644\u0629 \u0627\u0644\u0645\u0634\u062a\u0631\u064a\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_4630\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/ivyfragrance.com\/ar\/product\/blush-rose\/\">Blush Rose<\/a><\/h3>\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x639;.<\/span>&nbsp;19.00<\/bdi><\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-icons product-grid-item product type-product post-4274 status-publish instock product_cat-private-collection product_cat-special-offers has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"2\" data-id=\"4274\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/ivyfragrance.com\/ar\/product\/hakman\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Hakman\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/01\/IVY-V2-1024x1024.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/01\/IVY-V2-1024x1024.png 1024w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/01\/IVY-V2-300x300.png 300w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/01\/IVY-V2-150x150.png 150w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/01\/IVY-V2-768x768.png 768w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/01\/IVY-V2-12x12.png 12w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/01\/IVY-V2-800x800.png 800w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/01\/IVY-V2-400x400.png 400w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/01\/IVY-V2-600x600.png 600w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/01\/IVY-V2.png 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/01\/2-819x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/01\/2-819x1024.jpg 819w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/01\/2-240x300.jpg 240w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/01\/2-768x960.jpg 768w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/01\/2-1229x1536.jpg 1229w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/01\/2-1639x2048.jpg 1639w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/01\/2-10x12.jpg 10w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/01\/2-800x1000.jpg 800w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/01\/2-400x500.jpg 400w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/01\/2-600x750.jpg 600w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/01\/2-150x187.jpg 150w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/01\/2-scaled.jpg 2048w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"\/ar\/wp-json\/wp\/v2\/pages\/5?add-to-cart=4274\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_4274\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"4274\" data-product_sku=\"IVY-1063\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Hakman&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Hakman&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0633\u0644\u0629 \u0627\u0644\u0645\u0634\u062a\u0631\u064a\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_4274\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/ivyfragrance.com\/ar\/product\/hakman\/\">Hakman<\/a><\/h3>\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x639;.<\/span>&nbsp;37.00<\/bdi><\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-icons product-grid-item product type-product post-4633 status-publish last instock product_cat-perfume has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"3\" data-id=\"4633\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/ivyfragrance.com\/ar\/product\/passion-glow\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Passion Glow\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/IMG_1696-1024x1024.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/IMG_1696-1024x1024.png 1024w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/IMG_1696-300x300.png 300w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/IMG_1696-150x150.png 150w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/IMG_1696-768x768.png 768w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/IMG_1696-12x12.png 12w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/IMG_1696-400x400.png 400w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/IMG_1696-600x600.png 600w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/IMG_1696.png 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/46-1024x1024.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/46-1024x1024.png 1024w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/46-300x300.png 300w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/46-150x150.png 150w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/46-768x768.png 768w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/46-12x12.png 12w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/46-400x400.png 400w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/46-600x600.png 600w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/46.png 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"\/ar\/wp-json\/wp\/v2\/pages\/5?add-to-cart=4633\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_4633\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"4633\" data-product_sku=\"IVY-1017\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Passion Glow&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Passion Glow&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0633\u0644\u0629 \u0627\u0644\u0645\u0634\u062a\u0631\u064a\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_4633\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/ivyfragrance.com\/ar\/product\/passion-glow\/\">Passion Glow<\/a><\/h3>\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x639;.<\/span>&nbsp;20.00<\/bdi><\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"wd-nav-arrows wd-pos-sep wd-hover-1 wd-icon-1\">\n\t\t\t<div class=\"wd-btn-arrow wd-prev wd-disabled\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"wd-btn-arrow wd-next\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<div class=\"wd-nav-pagin-wrap text-center wd-style-shape wd-hide-md-sm wd-hide-sm\">\n\t\t\t<ul class=\"wd-nav-pagin\"><\/ul>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-d52fb82 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d52fb82\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-10bf4e2\" data-id=\"10bf4e2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-09610f9 elementor-widget elementor-widget-heading\" data-id=\"09610f9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">IVY Collection<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-abbb8e3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"abbb8e3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0ec8bb1\" data-id=\"0ec8bb1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dfd3ee1 wd-width-100 elementor-widget elementor-widget-wd_products\" data-id=\"dfd3ee1\" data-element_type=\"widget\" data-widget_type=\"wd_products.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\n\t\t\t<div id=\"carousel-105\" class=\"wd-carousel-container  wd-products-element wd-products products\">\n\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t<div class=\"wd-carousel-inner\">\n\t\t\t\t\t<div class=\"wd-carousel wd-grid\" style=\"--wd-col-lg:3;--wd-col-md:3;--wd-col-sm:2;--wd-gap-lg:0px;\">\n\t\t\t\t\t\t<div class=\"wd-carousel-wrap\">\n\t\t\t\t\t\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-icons product-grid-item product type-product post-578 status-publish outofstock product_cat-perfume product_cat-special-offers product_tag-perfume has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"1\" data-id=\"578\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/ivyfragrance.com\/ar\/product\/homie\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"\u0647\u0648\u0645\u064a\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"out-of-stock product-label\">Sold out<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/2-1024x1024.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/2-1024x1024.png 1024w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/2-300x300.png 300w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/2-150x150.png 150w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/2-768x768.png 768w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/2-12x12.png 12w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/2-800x800.png 800w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/2-400x400.png 400w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/2-600x600.png 600w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/2.png 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"681\" height=\"1024\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/3-681x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/3-681x1024.jpg 681w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/3-199x300.jpg 199w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/3-768x1156.jpg 768w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/3-1021x1536.jpg 1021w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/3-1361x2048.jpg 1361w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/3-8x12.jpg 8w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/3-800x1204.jpg 800w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/3-400x602.jpg 400w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/3-600x903.jpg 600w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/3-150x226.jpg 150w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/3-scaled.jpg 1701w\" sizes=\"auto, (max-width: 681px) 100vw, 681px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/ivyfragrance.com\/ar\/product\/homie\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_578\" data-quantity=\"1\" class=\"button product_type_simple add-to-cart-loop\" data-product_id=\"578\" data-product_sku=\"IVY-1001\" aria-label=\"\u0625\u0642\u0631\u0623 \u0627\u0644\u0645\u0632\u064a\u062f \u0639\u0646 \u201cHomie\u201d\" rel=\"nofollow\" data-success_message=\"\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u0632\u064a\u062f<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_578\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/ivyfragrance.com\/ar\/product\/homie\/\">\u0647\u0648\u0645\u064a<\/a><\/h3>\t\t\t\t\t\t\t\t\t\n\t\t\t\t<div class=\"star-rating\" role=\"img\" aria-label=\"\u062a\u0645 \u0627\u0644\u062a\u0642\u064a\u064a\u0645 5.00 \u0645\u0646 5\" data-no-translation-aria-label=\"\">\n\t\t\t\t\t<span style=\"width:100%\">\n\t\t\t\u062a\u0645 \u0627\u0644\u062a\u0642\u064a\u064a\u0645 <strong class=\"rating\">5.00<\/strong> \u0645\u0646 5\t\t<\/span>\n\t\t\t\t<\/div>\n\n\t\t\n\t\t\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x639;.<\/span>&nbsp;19.00<\/bdi><\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-icons product-grid-item product type-product post-929 status-publish instock product_cat-perfume product_cat-special-offers has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"2\" data-id=\"929\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/ivyfragrance.com\/ar\/product\/newday\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"\u0646\u064a\u0648\u062f\u064a\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/3-1024x1024.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/3-1024x1024.png 1024w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/3-300x300.png 300w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/3-150x150.png 150w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/3-768x768.png 768w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/3-12x12.png 12w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/3-800x800.png 800w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/3-400x400.png 400w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/3-600x600.png 600w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/3.png 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/4-683x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/4-683x1024.jpg 683w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/4-200x300.jpg 200w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/4-768x1152.jpg 768w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/4-1024x1536.jpg 1024w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/4-1365x2048.jpg 1365w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/4-8x12.jpg 8w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/4-800x1200.jpg 800w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/4-400x600.jpg 400w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/4-600x900.jpg 600w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/4-150x225.jpg 150w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/4-scaled.jpg 1707w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"\/ar\/wp-json\/wp\/v2\/pages\/5?add-to-cart=929\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_929\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"929\" data-product_sku=\"IVY-1008\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Newday&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Newday&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0633\u0644\u0629 \u0627\u0644\u0645\u0634\u062a\u0631\u064a\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_929\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/ivyfragrance.com\/ar\/product\/newday\/\">\u0646\u064a\u0648\u062f\u064a<\/a><\/h3>\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x639;.<\/span>&nbsp;20.00<\/bdi><\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-icons product-grid-item product type-product post-1423 status-publish last outofstock product_cat-perfume product_cat-special-offers has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"3\" data-id=\"1423\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/ivyfragrance.com\/ar\/product\/positano\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"\u0628\u0648\u0633\u064a\u062a\u0627\u0646\u0648\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"out-of-stock product-label\">Sold out<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/6-1024x1024.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/6-1024x1024.png 1024w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/6-300x300.png 300w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/6-150x150.png 150w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/6-768x768.png 768w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/6-12x12.png 12w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/6-800x800.png 800w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/6-400x400.png 400w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/6-600x600.png 600w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/6.png 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"1024\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/6-682x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/6-682x1024.jpg 682w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/6-200x300.jpg 200w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/6-768x1153.jpg 768w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/6-1023x1536.jpg 1023w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/6-1365x2048.jpg 1365w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/6-8x12.jpg 8w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/6-800x1201.jpg 800w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/6-400x600.jpg 400w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/6-600x901.jpg 600w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/6-150x225.jpg 150w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/6-scaled.jpg 1706w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/ivyfragrance.com\/ar\/product\/positano\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1423\" data-quantity=\"1\" class=\"button product_type_simple add-to-cart-loop\" data-product_id=\"1423\" data-product_sku=\"IVY-1011\" aria-label=\"\u0625\u0642\u0631\u0623 \u0627\u0644\u0645\u0632\u064a\u062f \u0639\u0646 \u201cPositano\u201d\" rel=\"nofollow\" data-success_message=\"\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u0632\u064a\u062f<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1423\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/ivyfragrance.com\/ar\/product\/positano\/\">\u0628\u0648\u0633\u064a\u062a\u0627\u0646\u0648<\/a><\/h3>\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x639;.<\/span>&nbsp;19.00<\/bdi><\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-icons product-grid-item product type-product post-35 status-publish first instock product_cat-perfume product_cat-special-offers product_tag-perfume has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"4\" data-id=\"35\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/ivyfragrance.com\/ar\/product\/dark-oud\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"\u062f\u0627\u0631\u0643 \u0639\u0648\u062f\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/1-1024x1024.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/1-1024x1024.png 1024w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/1-300x300.png 300w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/1-150x150.png 150w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/1-768x768.png 768w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/1-12x12.png 12w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/1-800x800.png 800w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/1-400x400.png 400w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/1-600x600.png 600w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2023\/07\/1.png 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"681\" height=\"1024\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/7-681x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/7-681x1024.jpg 681w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/7-200x300.jpg 200w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/7-768x1155.jpg 768w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/7-1022x1536.jpg 1022w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/7-1362x2048.jpg 1362w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/7-8x12.jpg 8w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/7-800x1203.jpg 800w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/7-400x601.jpg 400w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/7-600x902.jpg 600w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/7-150x226.jpg 150w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/7-scaled.jpg 1703w\" sizes=\"auto, (max-width: 681px) 100vw, 681px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"\/ar\/wp-json\/wp\/v2\/pages\/5?add-to-cart=35\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_35\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"35\" data-product_sku=\"IVY-1002\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Dark Oud&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Dark Oud&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0633\u0644\u0629 \u0627\u0644\u0645\u0634\u062a\u0631\u064a\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_35\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/ivyfragrance.com\/ar\/product\/dark-oud\/\">\u062f\u0627\u0631\u0643 \u0639\u0648\u062f<\/a><\/h3>\t\t\t\t\t\t\t\t\t\n\t\t\t\t<div class=\"star-rating\" role=\"img\" aria-label=\"\u062a\u0645 \u0627\u0644\u062a\u0642\u064a\u064a\u0645 5.00 \u0645\u0646 5\" data-no-translation-aria-label=\"\">\n\t\t\t\t\t<span style=\"width:100%\">\n\t\t\t\u062a\u0645 \u0627\u0644\u062a\u0642\u064a\u064a\u0645 <strong class=\"rating\">5.00<\/strong> \u0645\u0646 5\t\t<\/span>\n\t\t\t\t<\/div>\n\n\t\t\n\t\t\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x639;.<\/span>&nbsp;25.00<\/bdi><\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-icons product-grid-item product type-product post-38 status-publish outofstock product_cat-perfume product_cat-special-offers product_tag-perfume has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"5\" data-id=\"38\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/ivyfragrance.com\/ar\/product\/tobacco-coba\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"\u062a\u0648\u0628\u0627\u0643\u0648 \u0643\u064a\u0648\u0628\u0627\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"out-of-stock product-label\">Sold out<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/4-1024x1024.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/4-1024x1024.png 1024w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/4-300x300.png 300w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/4-150x150.png 150w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/4-768x768.png 768w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/4-12x12.png 12w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/4-800x800.png 800w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/4-400x400.png 400w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/4-600x600.png 600w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/4.png 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/5-683x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/5-683x1024.jpg 683w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/5-200x300.jpg 200w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/5-768x1151.jpg 768w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/5-1025x1536.jpg 1025w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/5-1366x2048.jpg 1366w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/5-8x12.jpg 8w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/5-800x1199.jpg 800w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/5-400x600.jpg 400w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/5-600x899.jpg 600w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/5-150x225.jpg 150w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/5-scaled.jpg 1708w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/ivyfragrance.com\/ar\/product\/tobacco-coba\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_38\" data-quantity=\"1\" class=\"button product_type_simple add-to-cart-loop\" data-product_id=\"38\" data-product_sku=\"IVY-1007\" aria-label=\"\u0625\u0642\u0631\u0623 \u0627\u0644\u0645\u0632\u064a\u062f \u0639\u0646 \u201cTobacco Cuba\u201d\" rel=\"nofollow\" data-success_message=\"\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u0632\u064a\u062f<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_38\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/ivyfragrance.com\/ar\/product\/tobacco-coba\/\">\u062a\u0648\u0628\u0627\u0643\u0648 \u0643\u064a\u0648\u0628\u0627<\/a><\/h3>\t\t\t\t\t\t\t\t\t\n\t\t\t\t<div class=\"star-rating\" role=\"img\" aria-label=\"\u062a\u0645 \u0627\u0644\u062a\u0642\u064a\u064a\u0645 5.00 \u0645\u0646 5\" data-no-translation-aria-label=\"\">\n\t\t\t\t\t<span style=\"width:100%\">\n\t\t\t\u062a\u0645 \u0627\u0644\u062a\u0642\u064a\u064a\u0645 <strong class=\"rating\">5.00<\/strong> \u0645\u0646 5\t\t<\/span>\n\t\t\t\t<\/div>\n\n\t\t\n\t\t\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x639;.<\/span>&nbsp;23.00<\/bdi><\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-icons product-grid-item product type-product post-2636 status-publish instock product_cat-perfume product_cat-special-offers has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"6\" data-id=\"2636\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/ivyfragrance.com\/ar\/product\/beach-villa-201\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"\u0628\u064a\u062a\u0634 \u0641\u064a\u0644\u0627 201\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/05\/5-1024x1024.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/05\/5-1024x1024.png 1024w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/05\/5-300x300.png 300w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/05\/5-150x150.png 150w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/05\/5-768x768.png 768w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/05\/5-12x12.png 12w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/05\/5-800x800.png 800w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/05\/5-400x400.png 400w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/05\/5-600x600.png 600w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/05\/5.png 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"681\" height=\"1024\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/05\/2-681x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/05\/2-681x1024.jpg 681w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/05\/2-200x300.jpg 200w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/05\/2-768x1155.jpg 768w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/05\/2-1022x1536.jpg 1022w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/05\/2-1362x2048.jpg 1362w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/05\/2-8x12.jpg 8w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/05\/2-800x1203.jpg 800w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/05\/2-400x601.jpg 400w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/05\/2-600x902.jpg 600w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/05\/2-150x225.jpg 150w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/05\/2-scaled.jpg 1703w\" sizes=\"auto, (max-width: 681px) 100vw, 681px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"\/ar\/wp-json\/wp\/v2\/pages\/5?add-to-cart=2636\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_2636\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"2636\" data-product_sku=\"IVY-1009\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Beach Villa 201&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Beach Villa 201&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0633\u0644\u0629 \u0627\u0644\u0645\u0634\u062a\u0631\u064a\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_2636\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/ivyfragrance.com\/ar\/product\/beach-villa-201\/\">\u0628\u064a\u062a\u0634 \u0641\u064a\u0644\u0627 201<\/a><\/h3>\t\t\t\t\t\t\t\t\t\n\t\t\t\t<div class=\"star-rating\" role=\"img\" aria-label=\"\u062a\u0645 \u0627\u0644\u062a\u0642\u064a\u064a\u0645 4.33 \u0645\u0646 5\" data-no-translation-aria-label=\"\">\n\t\t\t\t\t<span style=\"width:86.6%\">\n\t\t\t\u062a\u0645 \u0627\u0644\u062a\u0642\u064a\u064a\u0645 <strong class=\"rating\">4.33<\/strong> \u0645\u0646 5\t\t<\/span>\n\t\t\t\t<\/div>\n\n\t\t\n\t\t\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x639;.<\/span>&nbsp;20.00<\/bdi><\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-icons product-grid-item product type-product post-3471 status-publish last instock product_cat-perfume product_cat-special-offers has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"7\" data-id=\"3471\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/ivyfragrance.com\/ar\/product\/laos-patchouli\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Laos &amp; Patchouli\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/12\/Laos-1024x1024.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/12\/Laos-1024x1024.png 1024w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/12\/Laos-300x300.png 300w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/12\/Laos-150x150.png 150w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/12\/Laos-768x768.png 768w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/12\/Laos-12x12.png 12w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/12\/Laos-800x800.png 800w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/12\/Laos-400x400.png 400w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/12\/Laos-600x600.png 600w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/12\/Laos.png 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"546\" height=\"824\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/12\/laos2.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/12\/laos2.jpg 546w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/12\/laos2-199x300.jpg 199w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/12\/laos2-8x12.jpg 8w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/12\/laos2-400x604.jpg 400w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/12\/laos2-150x226.jpg 150w\" sizes=\"auto, (max-width: 546px) 100vw, 546px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"\/ar\/wp-json\/wp\/v2\/pages\/5?add-to-cart=3471\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_3471\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"3471\" data-product_sku=\"1054\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Laos &amp; Patchouli&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Laos &amp; Patchouli&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0633\u0644\u0629 \u0627\u0644\u0645\u0634\u062a\u0631\u064a\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_3471\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/ivyfragrance.com\/ar\/product\/laos-patchouli\/\">\u0644\u0627\u0648\u0633 \u0622\u0646\u062f \u0628\u062a\u0634\u0648\u0644\u064a<\/a><\/h3>\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x639;.<\/span>&nbsp;25.00<\/bdi><\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-icons product-grid-item product type-product post-3475 status-publish first outofstock product_cat-perfume product_cat-special-offers has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"8\" data-id=\"3475\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/ivyfragrance.com\/ar\/product\/last-quarter-moon\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"\u0644\u0627\u0633\u062a \u0643\u0648\u0627\u0631\u062a\u0631 \u0645\u0648\u0648\u0646\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"out-of-stock product-label\">Sold out<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/12\/Last-q-1024x1024.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/12\/Last-q-1024x1024.png 1024w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/12\/Last-q-300x300.png 300w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/12\/Last-q-150x150.png 150w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/12\/Last-q-768x768.png 768w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/12\/Last-q-12x12.png 12w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/12\/Last-q-800x800.png 800w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/12\/Last-q-400x400.png 400w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/12\/Last-q-600x600.png 600w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/12\/Last-q.png 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/ivyfragrance.com\/ar\/product\/last-quarter-moon\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_3475\" data-quantity=\"1\" class=\"button product_type_simple add-to-cart-loop\" data-product_id=\"3475\" data-product_sku=\"1053\" aria-label=\"\u0625\u0642\u0631\u0623 \u0627\u0644\u0645\u0632\u064a\u062f \u0639\u0646 \u201cLast Quarter Moon\u201d\" rel=\"nofollow\" data-success_message=\"\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u0632\u064a\u062f<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_3475\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/ivyfragrance.com\/ar\/product\/last-quarter-moon\/\">\u0644\u0627\u0633\u062a \u0643\u0648\u0627\u0631\u062a\u0631 \u0645\u0648\u0648\u0646<\/a><\/h3>\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x639;.<\/span>&nbsp;22.00<\/bdi><\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-icons product-grid-item product type-product post-4071 status-publish outofstock product_cat-premium-collection product_cat-special-offers has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"9\" data-id=\"4071\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/ivyfragrance.com\/ar\/product\/desert-walk\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Desert walk\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"out-of-stock product-label\">Sold out<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/11\/IVY-V2--1024x1024.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/11\/IVY-V2--1024x1024.png 1024w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/11\/IVY-V2--300x300.png 300w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/11\/IVY-V2--150x150.png 150w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/11\/IVY-V2--768x768.png 768w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/11\/IVY-V2--12x12.png 12w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/11\/IVY-V2--800x800.png 800w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/11\/IVY-V2--400x400.png 400w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/11\/IVY-V2--600x600.png 600w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/11\/IVY-V2-.png 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/11\/5-819x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/11\/5-819x1024.jpg 819w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/11\/5-240x300.jpg 240w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/11\/5-768x960.jpg 768w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/11\/5-1229x1536.jpg 1229w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/11\/5-1638x2048.jpg 1638w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/11\/5-10x12.jpg 10w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/11\/5-800x1000.jpg 800w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/11\/5-400x500.jpg 400w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/11\/5-600x750.jpg 600w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/11\/5-150x188.jpg 150w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/11\/5-scaled.jpg 2048w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/ivyfragrance.com\/ar\/product\/desert-walk\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_4071\" data-quantity=\"1\" class=\"button product_type_simple add-to-cart-loop\" data-product_id=\"4071\" data-product_sku=\"IVY-1014\" aria-label=\"\u0625\u0642\u0631\u0623 \u0627\u0644\u0645\u0632\u064a\u062f \u0639\u0646 \u201cDesert walk\u201d\" rel=\"nofollow\" data-success_message=\"\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u0632\u064a\u062f<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_4071\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/ivyfragrance.com\/ar\/product\/desert-walk\/\">Desert walk<\/a><\/h3>\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x639;.<\/span>&nbsp;27.00<\/bdi><\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-icons product-grid-item product type-product post-4073 status-publish instock product_cat-premium-collection product_cat-special-offers has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"10\" data-id=\"4073\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/ivyfragrance.com\/ar\/product\/ivy-noir\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Ivy Noir\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/11\/IVY-V2-40-1024x1024.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/11\/IVY-V2-40-1024x1024.png 1024w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/11\/IVY-V2-40-300x300.png 300w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/11\/IVY-V2-40-150x150.png 150w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/11\/IVY-V2-40-768x768.png 768w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/11\/IVY-V2-40-12x12.png 12w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/11\/IVY-V2-40-800x800.png 800w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/11\/IVY-V2-40-400x400.png 400w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/11\/IVY-V2-40-600x600.png 600w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/11\/IVY-V2-40.png 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/11\/2-819x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/11\/2-819x1024.jpg 819w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/11\/2-240x300.jpg 240w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/11\/2-768x960.jpg 768w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/11\/2-1229x1536.jpg 1229w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/11\/2-1638x2048.jpg 1638w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/11\/2-10x12.jpg 10w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/11\/2-800x1000.jpg 800w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/11\/2-400x500.jpg 400w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/11\/2-600x750.jpg 600w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/11\/2-150x188.jpg 150w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/11\/2-scaled.jpg 2048w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"\/ar\/wp-json\/wp\/v2\/pages\/5?add-to-cart=4073\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_4073\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"4073\" data-product_sku=\"IVY-1015\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Ivy Noir&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Ivy Noir&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0633\u0644\u0629 \u0627\u0644\u0645\u0634\u062a\u0631\u064a\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_4073\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/ivyfragrance.com\/ar\/product\/ivy-noir\/\">Ivy Noir<\/a><\/h3>\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x639;.<\/span>&nbsp;24.00<\/bdi><\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-icons product-grid-item product type-product post-4630 status-publish last instock product_cat-perfume has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"11\" data-id=\"4630\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/ivyfragrance.com\/ar\/product\/blush-rose\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Blush Rose\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/IMG_1697-1024x1024.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/IMG_1697-1024x1024.png 1024w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/IMG_1697-300x300.png 300w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/IMG_1697-150x150.png 150w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/IMG_1697-768x768.png 768w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/IMG_1697-12x12.png 12w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/IMG_1697-400x400.png 400w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/IMG_1697-600x600.png 600w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/IMG_1697.png 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/48-1024x1024.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/48-1024x1024.png 1024w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/48-300x300.png 300w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/48-150x150.png 150w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/48-768x768.png 768w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/48-12x12.png 12w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/48-400x400.png 400w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/48-600x600.png 600w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/48.png 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"\/ar\/wp-json\/wp\/v2\/pages\/5?add-to-cart=4630\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_4630\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"4630\" data-product_sku=\"IVY-1016\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Blush Rose&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Blush Rose&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0633\u0644\u0629 \u0627\u0644\u0645\u0634\u062a\u0631\u064a\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_4630\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/ivyfragrance.com\/ar\/product\/blush-rose\/\">Blush Rose<\/a><\/h3>\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x639;.<\/span>&nbsp;19.00<\/bdi><\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-icons product-grid-item product type-product post-4633 status-publish first instock product_cat-perfume has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"12\" data-id=\"4633\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/ivyfragrance.com\/ar\/product\/passion-glow\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Passion Glow\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/IMG_1696-1024x1024.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/IMG_1696-1024x1024.png 1024w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/IMG_1696-300x300.png 300w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/IMG_1696-150x150.png 150w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/IMG_1696-768x768.png 768w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/IMG_1696-12x12.png 12w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/IMG_1696-400x400.png 400w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/IMG_1696-600x600.png 600w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/IMG_1696.png 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/46-1024x1024.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/46-1024x1024.png 1024w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/46-300x300.png 300w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/46-150x150.png 150w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/46-768x768.png 768w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/46-12x12.png 12w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/46-400x400.png 400w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/46-600x600.png 600w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/04\/46.png 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"\/ar\/wp-json\/wp\/v2\/pages\/5?add-to-cart=4633\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_4633\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"4633\" data-product_sku=\"IVY-1017\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Passion Glow&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Passion Glow&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0633\u0644\u0629 \u0627\u0644\u0645\u0634\u062a\u0631\u064a\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_4633\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/ivyfragrance.com\/ar\/product\/passion-glow\/\">Passion Glow<\/a><\/h3>\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x639;.<\/span>&nbsp;20.00<\/bdi><\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"wd-nav-arrows wd-pos-sep wd-hover-1 wd-icon-1\">\n\t\t\t<div class=\"wd-btn-arrow wd-prev wd-disabled\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"wd-btn-arrow wd-next\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-fedf0db elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fedf0db\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dcc5fd1\" data-id=\"dcc5fd1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-4ce4200 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4ce4200\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-823825d\" data-id=\"823825d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-79fd083 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"79fd083\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9106b7b\" data-id=\"9106b7b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f543e83 elementor-widget elementor-widget-heading\" data-id=\"f543e83\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">\u0627\u0644\u0645\u062c\u0645\u0648\u0639\u0629 \u0627\u0644\u062e\u0627\u0635\u0629<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-fb9155b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fb9155b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1710987\" data-id=\"1710987\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0fd7ffc wd-width-100 elementor-widget elementor-widget-wd_products\" data-id=\"0fd7ffc\" data-element_type=\"widget\" data-widget_type=\"wd_products.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\n\t\t\t<div id=\"carousel-859\" class=\"wd-carousel-container  wd-products-element wd-products products\">\n\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t<div class=\"wd-carousel-inner\">\n\t\t\t\t\t<div class=\"wd-carousel wd-grid\" style=\"--wd-col-lg:3;--wd-col-md:3;--wd-col-sm:2;--wd-gap-lg:0px;\">\n\t\t\t\t\t\t<div class=\"wd-carousel-wrap\">\n\t\t\t\t\t\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-icons product-grid-item product type-product post-3626 status-publish instock product_cat-perfume product_cat-special-offers has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"1\" data-id=\"3626\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/ivyfragrance.com\/ar\/product\/eastern-rose\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Eastern Rose\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/Easter-rose-sq-1024x1024.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/Easter-rose-sq-1024x1024.png 1024w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/Easter-rose-sq-300x300.png 300w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/Easter-rose-sq-150x150.png 150w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/Easter-rose-sq-768x768.png 768w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/Easter-rose-sq-12x12.png 12w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/Easter-rose-sq-800x800.png 800w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/Easter-rose-sq-400x400.png 400w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/Easter-rose-sq-600x600.png 600w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/Easter-rose-sq.png 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/3-819x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/3-819x1024.jpg 819w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/3-240x300.jpg 240w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/3-768x960.jpg 768w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/3-1229x1536.jpg 1229w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/3-1638x2048.jpg 1638w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/3-10x12.jpg 10w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/3-800x1000.jpg 800w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/3-400x500.jpg 400w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/3-600x750.jpg 600w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/3-150x188.jpg 150w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/3-scaled.jpg 2048w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"\/ar\/wp-json\/wp\/v2\/pages\/5?add-to-cart=3626\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_3626\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"3626\" data-product_sku=\"IVY-1056\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Eastern Rose&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Eastern Rose&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0633\u0644\u0629 \u0627\u0644\u0645\u0634\u062a\u0631\u064a\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_3626\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/ivyfragrance.com\/ar\/product\/eastern-rose\/\">Eastern Rose<\/a><\/h3>\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x639;.<\/span>&nbsp;35.00<\/bdi><\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-icons product-grid-item product type-product post-3629 status-publish instock product_cat-perfume product_cat-special-offers has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"2\" data-id=\"3629\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/ivyfragrance.com\/ar\/product\/mystic-path\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Mystic Path\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/Mystic-Path-sq-1-1024x1024.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/Mystic-Path-sq-1-1024x1024.png 1024w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/Mystic-Path-sq-1-300x300.png 300w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/Mystic-Path-sq-1-150x150.png 150w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/Mystic-Path-sq-1-768x768.png 768w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/Mystic-Path-sq-1-12x12.png 12w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/Mystic-Path-sq-1-800x800.png 800w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/Mystic-Path-sq-1-400x400.png 400w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/Mystic-Path-sq-1-600x600.png 600w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/Mystic-Path-sq-1.png 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/4-819x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/4-819x1024.jpg 819w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/4-240x300.jpg 240w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/4-768x960.jpg 768w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/4-1229x1536.jpg 1229w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/4-1638x2048.jpg 1638w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/4-10x12.jpg 10w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/4-800x1000.jpg 800w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/4-400x500.jpg 400w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/4-600x750.jpg 600w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/4-150x188.jpg 150w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/4-scaled.jpg 2048w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"\/ar\/wp-json\/wp\/v2\/pages\/5?add-to-cart=3629\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_3629\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"3629\" data-product_sku=\"IVY-1055\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Mystic Path&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Mystic Path&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0633\u0644\u0629 \u0627\u0644\u0645\u0634\u062a\u0631\u064a\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_3629\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/ivyfragrance.com\/ar\/product\/mystic-path\/\">Mystic Path<\/a><\/h3>\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x639;.<\/span>&nbsp;32.00<\/bdi><\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-icons product-grid-item product type-product post-4274 status-publish last instock product_cat-private-collection product_cat-special-offers has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"3\" data-id=\"4274\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/ivyfragrance.com\/ar\/product\/hakman\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Hakman\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/01\/IVY-V2-1024x1024.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/01\/IVY-V2-1024x1024.png 1024w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/01\/IVY-V2-300x300.png 300w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/01\/IVY-V2-150x150.png 150w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/01\/IVY-V2-768x768.png 768w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/01\/IVY-V2-12x12.png 12w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/01\/IVY-V2-800x800.png 800w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/01\/IVY-V2-400x400.png 400w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/01\/IVY-V2-600x600.png 600w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/01\/IVY-V2.png 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/01\/2-819x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/01\/2-819x1024.jpg 819w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/01\/2-240x300.jpg 240w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/01\/2-768x960.jpg 768w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/01\/2-1229x1536.jpg 1229w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/01\/2-1639x2048.jpg 1639w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/01\/2-10x12.jpg 10w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/01\/2-800x1000.jpg 800w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/01\/2-400x500.jpg 400w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/01\/2-600x750.jpg 600w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/01\/2-150x187.jpg 150w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/01\/2-scaled.jpg 2048w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"\/ar\/wp-json\/wp\/v2\/pages\/5?add-to-cart=4274\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_4274\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"4274\" data-product_sku=\"IVY-1063\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Hakman&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Hakman&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0633\u0644\u0629 \u0627\u0644\u0645\u0634\u062a\u0631\u064a\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_4274\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/ivyfragrance.com\/ar\/product\/hakman\/\">Hakman<\/a><\/h3>\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x639;.<\/span>&nbsp;37.00<\/bdi><\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"wd-nav-arrows wd-pos-sep wd-hover-1 wd-icon-1\">\n\t\t\t<div class=\"wd-btn-arrow wd-prev wd-disabled\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"wd-btn-arrow wd-next\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-768395e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"768395e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-650e20e\" data-id=\"650e20e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6b875bf elementor-widget elementor-widget-heading\" data-id=\"6b875bf\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Body FRAGRANCES &amp; Home Fragrance<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-e2c5db0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e2c5db0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4dd2138\" data-id=\"4dd2138\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-07b4dda wd-width-100 elementor-widget elementor-widget-wd_products\" data-id=\"07b4dda\" data-element_type=\"widget\" data-widget_type=\"wd_products.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\n\t\t\t<div id=\"carousel-467\" class=\"wd-carousel-container  wd-products-element wd-products products\">\n\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t<div class=\"wd-carousel-inner\">\n\t\t\t\t\t<div class=\"wd-carousel wd-grid\" style=\"--wd-col-lg:3;--wd-col-md:3;--wd-col-sm:2;--wd-gap-lg:0px;\">\n\t\t\t\t\t\t<div class=\"wd-carousel-wrap\">\n\t\t\t\t\t\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-icons product-grid-item product type-product post-1910 status-publish outofstock product_cat-home-fragrance product_cat-special-offers has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"1\" data-id=\"1910\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/ivyfragrance.com\/ar\/product\/body-soul\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"BODY &amp; SOUL (white)\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"out-of-stock product-label\">Sold out<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/01\/53509138-afc2-4ff2-8fd2-dcc5ade74349-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/01\/53509138-afc2-4ff2-8fd2-dcc5ade74349-1024x1024.jpg 1024w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/01\/53509138-afc2-4ff2-8fd2-dcc5ade74349-300x300.jpg 300w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/01\/53509138-afc2-4ff2-8fd2-dcc5ade74349-150x150.jpg 150w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/01\/53509138-afc2-4ff2-8fd2-dcc5ade74349-768x768.jpg 768w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/01\/53509138-afc2-4ff2-8fd2-dcc5ade74349-12x12.jpg 12w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/01\/53509138-afc2-4ff2-8fd2-dcc5ade74349-800x800.jpg 800w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/01\/53509138-afc2-4ff2-8fd2-dcc5ade74349-400x400.jpg 400w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/01\/53509138-afc2-4ff2-8fd2-dcc5ade74349-600x600.jpg 600w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/01\/53509138-afc2-4ff2-8fd2-dcc5ade74349.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/01\/b5cf8606-227b-4188-8eea-fcd2b33ca756-819x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/01\/b5cf8606-227b-4188-8eea-fcd2b33ca756-819x1024.jpg 819w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/01\/b5cf8606-227b-4188-8eea-fcd2b33ca756-240x300.jpg 240w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/01\/b5cf8606-227b-4188-8eea-fcd2b33ca756-768x960.jpg 768w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/01\/b5cf8606-227b-4188-8eea-fcd2b33ca756-1229x1536.jpg 1229w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/01\/b5cf8606-227b-4188-8eea-fcd2b33ca756-10x12.jpg 10w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/01\/b5cf8606-227b-4188-8eea-fcd2b33ca756-800x1000.jpg 800w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/01\/b5cf8606-227b-4188-8eea-fcd2b33ca756-400x500.jpg 400w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/01\/b5cf8606-227b-4188-8eea-fcd2b33ca756-600x750.jpg 600w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/01\/b5cf8606-227b-4188-8eea-fcd2b33ca756-150x188.jpg 150w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/01\/b5cf8606-227b-4188-8eea-fcd2b33ca756.jpg 1280w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/ivyfragrance.com\/ar\/product\/body-soul\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_1910\" data-quantity=\"1\" class=\"button product_type_simple add-to-cart-loop\" data-product_id=\"1910\" data-product_sku=\"IVY-1040\" aria-label=\"\u0625\u0642\u0631\u0623 \u0627\u0644\u0645\u0632\u064a\u062f \u0639\u0646 \u201cBODY &amp; SOUL (white)\u201d\" rel=\"nofollow\" data-success_message=\"\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u0632\u064a\u062f<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1910\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/ivyfragrance.com\/ar\/product\/body-soul\/\">\u0628\u0648\u062f\u064a \u0623\u0646\u062f \u0633\u0648\u0644 (\u0623\u0628\u064a\u0636)<\/a><\/h3>\t\t\t\t\t\t\t\t\t\n\t\t\t\t<div class=\"star-rating\" role=\"img\" aria-label=\"\u062a\u0645 \u0627\u0644\u062a\u0642\u064a\u064a\u0645 5.00 \u0645\u0646 5\" data-no-translation-aria-label=\"\">\n\t\t\t\t\t<span style=\"width:100%\">\n\t\t\t\u062a\u0645 \u0627\u0644\u062a\u0642\u064a\u064a\u0645 <strong class=\"rating\">5.00<\/strong> \u0645\u0646 5\t\t<\/span>\n\t\t\t\t<\/div>\n\n\t\t\n\t\t\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x639;.<\/span>&nbsp;14.00<\/bdi><\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-icons product-grid-item product type-product post-3045 status-publish instock product_cat-home-fragrance product_cat-special-offers has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"2\" data-id=\"3045\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/ivyfragrance.com\/ar\/product\/body-soul-2\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Body &amp; Soul 2 (blue)\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/06\/DODY-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/06\/DODY-1024x1024.jpg 1024w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/06\/DODY-300x300.jpg 300w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/06\/DODY-150x150.jpg 150w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/06\/DODY-768x768.jpg 768w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/06\/DODY-12x12.jpg 12w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/06\/DODY-800x800.jpg 800w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/06\/DODY-400x400.jpg 400w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/06\/DODY-600x600.jpg 600w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2024\/06\/DODY.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"\/ar\/wp-json\/wp\/v2\/pages\/5?add-to-cart=3045\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_3045\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"3045\" data-product_sku=\"IVY-1041\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Body &amp; Soul 2 (blue)&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Body &amp; Soul 2 (blue)&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0633\u0644\u0629 \u0627\u0644\u0645\u0634\u062a\u0631\u064a\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_3045\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/ivyfragrance.com\/ar\/product\/body-soul-2\/\">\u0628\u0648\u062f\u064a \u0623\u0646\u062f \u0633\u0648\u0644 2 (\u0623\u0632\u0631\u0642)<\/a><\/h3>\t\t\t\t\t\t\t\t\t\n\t\t\t\t<div class=\"star-rating\" role=\"img\" aria-label=\"\u062a\u0645 \u0627\u0644\u062a\u0642\u064a\u064a\u0645 5.00 \u0645\u0646 5\" data-no-translation-aria-label=\"\">\n\t\t\t\t\t<span style=\"width:100%\">\n\t\t\t\u062a\u0645 \u0627\u0644\u062a\u0642\u064a\u064a\u0645 <strong class=\"rating\">5.00<\/strong> \u0645\u0646 5\t\t<\/span>\n\t\t\t\t<\/div>\n\n\t\t\n\t\t\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x639;.<\/span>&nbsp;14.00<\/bdi><\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-icons product-grid-item product type-product post-3623 status-publish last instock product_cat-home-fragrance product_cat-special-offers has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"3\" data-id=\"3623\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/ivyfragrance.com\/ar\/product\/body-soul-4-peach\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Body &amp; Soul 4 (Peach)\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2026-01-11-at-6.14.54-PM-1024x1024.jpeg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2026-01-11-at-6.14.54-PM-1024x1024.jpeg 1024w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2026-01-11-at-6.14.54-PM-300x300.jpeg 300w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2026-01-11-at-6.14.54-PM-150x150.jpeg 150w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2026-01-11-at-6.14.54-PM-768x768.jpeg 768w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2026-01-11-at-6.14.54-PM-12x12.jpeg 12w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2026-01-11-at-6.14.54-PM-800x800.jpeg 800w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2026-01-11-at-6.14.54-PM-400x400.jpeg 400w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2026-01-11-at-6.14.54-PM-600x600.jpeg 600w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2026-01-11-at-6.14.54-PM.jpeg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/7-819x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/7-819x1024.jpg 819w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/7-240x300.jpg 240w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/7-768x960.jpg 768w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/7-1229x1536.jpg 1229w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/7-1638x2048.jpg 1638w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/7-10x12.jpg 10w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/7-800x1000.jpg 800w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/7-400x500.jpg 400w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/7-600x750.jpg 600w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/7-150x188.jpg 150w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/7-scaled.jpg 2048w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"\/ar\/wp-json\/wp\/v2\/pages\/5?add-to-cart=3623\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_3623\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"3623\" data-product_sku=\"IVY-1044\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Body &amp; Soul 4 (Peach)&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Body &amp; Soul 4 (Peach)&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0633\u0644\u0629 \u0627\u0644\u0645\u0634\u062a\u0631\u064a\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_3623\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/ivyfragrance.com\/ar\/product\/body-soul-4-peach\/\">Body &amp; Soul 4 (Peach)<\/a><\/h3>\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x639;.<\/span>&nbsp;14.00<\/bdi><\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-icons product-grid-item product type-product post-3541 status-publish first outofstock product_cat-home-fragrance product_cat-special-offers has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"4\" data-id=\"3541\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/ivyfragrance.com\/ar\/product\/body-soul-oud-bronze\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Body &amp; soul Oud (Bronze)\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"out-of-stock product-label\">Sold out<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/01\/oud-1024x1024.jpeg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/01\/oud-1024x1024.jpeg 1024w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/01\/oud-300x300.jpeg 300w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/01\/oud-150x150.jpeg 150w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/01\/oud-768x768.jpeg 768w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/01\/oud-12x12.jpeg 12w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/01\/oud-800x800.jpeg 800w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/01\/oud-400x400.jpeg 400w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/01\/oud-600x600.jpeg 600w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/01\/oud.jpeg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/ivyfragrance.com\/ar\/product\/body-soul-oud-bronze\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_3541\" data-quantity=\"1\" class=\"button product_type_simple add-to-cart-loop\" data-product_id=\"3541\" data-product_sku=\"IVY-1042\" aria-label=\"\u0625\u0642\u0631\u0623 \u0627\u0644\u0645\u0632\u064a\u062f \u0639\u0646 \u201cBody &amp; soul Oud (Bronze)\u201d\" rel=\"nofollow\" data-success_message=\"\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u0632\u064a\u062f<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_3541\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/ivyfragrance.com\/ar\/product\/body-soul-oud-bronze\/\">Body &amp; soul Oud (Bronze)<\/a><\/h3>\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x639;.<\/span>&nbsp;18.00<\/bdi><\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-icons product-grid-item product type-product post-3621 status-publish instock product_cat-home-fragrance product_cat-special-offers has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"5\" data-id=\"3621\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/ivyfragrance.com\/ar\/product\/body-and-soul-3-green\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Body and Soul 3 (Green)\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-24-at-7.42.58-PM-1024x1024.jpeg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-24-at-7.42.58-PM-1024x1024.jpeg 1024w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-24-at-7.42.58-PM-300x300.jpeg 300w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-24-at-7.42.58-PM-150x150.jpeg 150w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-24-at-7.42.58-PM-768x768.jpeg 768w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-24-at-7.42.58-PM-12x12.jpeg 12w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-24-at-7.42.58-PM-800x800.jpeg 800w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-24-at-7.42.58-PM-400x400.jpeg 400w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-24-at-7.42.58-PM-600x600.jpeg 600w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-24-at-7.42.58-PM.jpeg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/9-819x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/9-819x1024.jpg 819w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/9-240x300.jpg 240w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/9-768x960.jpg 768w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/9-1229x1536.jpg 1229w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/9-1638x2048.jpg 1638w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/9-10x12.jpg 10w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/9-800x1000.jpg 800w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/9-400x500.jpg 400w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/9-600x750.jpg 600w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/9-150x188.jpg 150w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/02\/9-scaled.jpg 2048w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"\/ar\/wp-json\/wp\/v2\/pages\/5?add-to-cart=3621\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_3621\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"3621\" data-product_sku=\"IVY-1043\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Body and Soul 3 (Green)&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Body and Soul 3 (Green)&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0633\u0644\u0629 \u0627\u0644\u0645\u0634\u062a\u0631\u064a\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_3621\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/ivyfragrance.com\/ar\/product\/body-and-soul-3-green\/\">Body and Soul 3 (Green)<\/a><\/h3>\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x639;.<\/span>&nbsp;14.00<\/bdi><\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-icons product-grid-item product type-product post-4168 status-publish instock product_cat-special-offers has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"6\" data-id=\"4168\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/ivyfragrance.com\/ar\/product\/body-lotion-1-white\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Body Lotion 1 &#8221; White&#8221;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/12\/IVY-Fragrances-1024x1024.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/12\/IVY-Fragrances-1024x1024.png 1024w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/12\/IVY-Fragrances-300x300.png 300w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/12\/IVY-Fragrances-150x150.png 150w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/12\/IVY-Fragrances-768x768.png 768w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/12\/IVY-Fragrances-12x12.png 12w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/12\/IVY-Fragrances-800x800.png 800w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/12\/IVY-Fragrances-400x400.png 400w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/12\/IVY-Fragrances-600x600.png 600w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/12\/IVY-Fragrances.png 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"\/ar\/wp-json\/wp\/v2\/pages\/5?add-to-cart=4168\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_4168\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"4168\" data-product_sku=\"IVY-1045\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Body Lotion 1 &quot; White&quot;&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Body Lotion 1 &quot; White&quot;&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0633\u0644\u0629 \u0627\u0644\u0645\u0634\u062a\u0631\u064a\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_4168\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/ivyfragrance.com\/ar\/product\/body-lotion-1-white\/\">Body Lotion 1 &#8221; White&#8221;<\/a><\/h3>\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x639;.<\/span>&nbsp;12.00<\/bdi><\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-icons product-grid-item product type-product post-4171 status-publish last instock product_cat-perfume product_cat-special-offers has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"7\" data-id=\"4171\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/ivyfragrance.com\/ar\/product\/body-lotion-2-blue\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Body Lotion 2 &#8221; Blue&#8221;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/12\/IVY-V21-1024x1024.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/12\/IVY-V21-1024x1024.png 1024w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/12\/IVY-V21-300x300.png 300w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/12\/IVY-V21-150x150.png 150w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/12\/IVY-V21-768x768.png 768w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/12\/IVY-V21-12x12.png 12w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/12\/IVY-V21-800x800.png 800w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/12\/IVY-V21-400x400.png 400w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/12\/IVY-V21-600x600.png 600w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/12\/IVY-V21.png 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"\/ar\/wp-json\/wp\/v2\/pages\/5?add-to-cart=4171\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_4171\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"4171\" data-product_sku=\"IVY-1046\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Body Lotion 2 &quot; Blue&quot;&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Body Lotion 2 &quot; Blue&quot;&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0633\u0644\u0629 \u0627\u0644\u0645\u0634\u062a\u0631\u064a\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_4171\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/ivyfragrance.com\/ar\/product\/body-lotion-2-blue\/\">Body Lotion 2 &#8221; Blue&#8221;<\/a><\/h3>\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x639;.<\/span>&nbsp;12.00<\/bdi><\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-icons product-grid-item product type-product post-3538 status-publish first instock product_cat-home-fragrance product_cat-special-offers has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"8\" data-id=\"3538\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/ivyfragrance.com\/ar\/product\/laskara\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Laskara\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/01\/laskara-1024x1024.jpeg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/01\/laskara-1024x1024.jpeg 1024w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/01\/laskara-300x300.jpeg 300w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/01\/laskara-150x150.jpeg 150w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/01\/laskara-768x768.jpeg 768w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/01\/laskara-12x12.jpeg 12w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/01\/laskara-800x800.jpeg 800w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/01\/laskara-400x400.jpeg 400w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/01\/laskara-600x600.jpeg 600w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/01\/laskara.jpeg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"\/ar\/wp-json\/wp\/v2\/pages\/5?add-to-cart=3538\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_3538\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"3538\" data-product_sku=\"IVY-1012\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Laskara&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Laskara&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0633\u0644\u0629 \u0627\u0644\u0645\u0634\u062a\u0631\u064a\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_3538\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/ivyfragrance.com\/ar\/product\/laskara\/\">Laskara<\/a><\/h3>\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x639;.<\/span>&nbsp;12.00<\/bdi><\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-icons product-grid-item product type-product post-46 status-publish outofstock product_cat-home-fragrance product_cat-special-offers product_tag-home-fragrance has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"9\" data-id=\"46\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/ivyfragrance.com\/ar\/product\/nature-blend\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"\u0646\u0627\u062a\u0634\u0631 \u0628\u0644\u0646\u062f\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"out-of-stock product-label\">Sold out<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/4e08d5dd-bf65-4e7f-958f-535a7292afe8-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/4e08d5dd-bf65-4e7f-958f-535a7292afe8-1024x1024.jpg 1024w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/4e08d5dd-bf65-4e7f-958f-535a7292afe8-300x300.jpg 300w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/4e08d5dd-bf65-4e7f-958f-535a7292afe8-150x150.jpg 150w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/4e08d5dd-bf65-4e7f-958f-535a7292afe8-768x768.jpg 768w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/4e08d5dd-bf65-4e7f-958f-535a7292afe8-12x12.jpg 12w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/4e08d5dd-bf65-4e7f-958f-535a7292afe8-800x800.jpg 800w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/4e08d5dd-bf65-4e7f-958f-535a7292afe8-400x400.jpg 400w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/4e08d5dd-bf65-4e7f-958f-535a7292afe8-600x600.jpg 600w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/4e08d5dd-bf65-4e7f-958f-535a7292afe8.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"818\" height=\"1024\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/15f9bcb5-7023-4848-8ad1-2d455a9bfca3-818x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/15f9bcb5-7023-4848-8ad1-2d455a9bfca3-818x1024.jpg 818w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/15f9bcb5-7023-4848-8ad1-2d455a9bfca3-240x300.jpg 240w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/15f9bcb5-7023-4848-8ad1-2d455a9bfca3-768x962.jpg 768w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/15f9bcb5-7023-4848-8ad1-2d455a9bfca3-1227x1536.jpg 1227w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/15f9bcb5-7023-4848-8ad1-2d455a9bfca3-10x12.jpg 10w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/15f9bcb5-7023-4848-8ad1-2d455a9bfca3-800x1002.jpg 800w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/15f9bcb5-7023-4848-8ad1-2d455a9bfca3-400x501.jpg 400w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/15f9bcb5-7023-4848-8ad1-2d455a9bfca3-600x751.jpg 600w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/15f9bcb5-7023-4848-8ad1-2d455a9bfca3-150x188.jpg 150w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/15f9bcb5-7023-4848-8ad1-2d455a9bfca3.jpg 1278w\" sizes=\"auto, (max-width: 818px) 100vw, 818px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/ivyfragrance.com\/ar\/product\/nature-blend\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_46\" data-quantity=\"1\" class=\"button product_type_simple add-to-cart-loop\" data-product_id=\"46\" data-product_sku=\"IVY-1005\" aria-label=\"\u0625\u0642\u0631\u0623 \u0627\u0644\u0645\u0632\u064a\u062f \u0639\u0646 \u201cNature Blend\u201d\" rel=\"nofollow\" data-success_message=\"\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u0632\u064a\u062f<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_46\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/ivyfragrance.com\/ar\/product\/nature-blend\/\">\u0646\u0627\u062a\u0634\u0631 \u0628\u0644\u0646\u062f<\/a><\/h3>\t\t\t\t\t\t\t\t\t\n\t\t\t\t<div class=\"star-rating\" role=\"img\" aria-label=\"\u062a\u0645 \u0627\u0644\u062a\u0642\u064a\u064a\u0645 5.00 \u0645\u0646 5\" data-no-translation-aria-label=\"\">\n\t\t\t\t\t<span style=\"width:100%\">\n\t\t\t\u062a\u0645 \u0627\u0644\u062a\u0642\u064a\u064a\u0645 <strong class=\"rating\">5.00<\/strong> \u0645\u0646 5\t\t<\/span>\n\t\t\t\t<\/div>\n\n\t\t\n\t\t\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x639;.<\/span>&nbsp;12.00<\/bdi><\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-icons product-grid-item product type-product post-3815 status-publish instock product_cat-perfume product_cat-special-offers has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"10\" data-id=\"3815\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/ivyfragrance.com\/ar\/product\/peach-iv-powder\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Peach IV &#8220;Powder&#8221;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-22-at-3.12.07-PM-1024x1024.jpeg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-22-at-3.12.07-PM-1024x1024.jpeg 1024w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-22-at-3.12.07-PM-300x300.jpeg 300w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-22-at-3.12.07-PM-150x150.jpeg 150w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-22-at-3.12.07-PM-768x768.jpeg 768w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-22-at-3.12.07-PM-12x12.jpeg 12w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-22-at-3.12.07-PM-800x800.jpeg 800w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-22-at-3.12.07-PM-400x400.jpeg 400w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-22-at-3.12.07-PM-600x600.jpeg 600w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-22-at-3.12.07-PM.jpeg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/05\/9-819x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/05\/9-819x1024.jpg 819w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/05\/9-240x300.jpg 240w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/05\/9-768x960.jpg 768w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/05\/9-1229x1536.jpg 1229w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/05\/9-1638x2048.jpg 1638w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/05\/9-10x12.jpg 10w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/05\/9-800x1000.jpg 800w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/05\/9-400x500.jpg 400w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/05\/9-600x750.jpg 600w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/05\/9-150x188.jpg 150w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/05\/9-scaled.jpg 2048w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"\/ar\/wp-json\/wp\/v2\/pages\/5?add-to-cart=3815\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_3815\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"3815\" data-product_sku=\"IVY-1057\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Peach IV &quot;Powder&quot;&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Peach IV &quot;Powder&quot;&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0633\u0644\u0629 \u0627\u0644\u0645\u0634\u062a\u0631\u064a\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_3815\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/ivyfragrance.com\/ar\/product\/peach-iv-powder\/\">Peach IV &#8220;Powder&#8221;<\/a><\/h3>\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x639;.<\/span>&nbsp;16.00<\/bdi><\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-icons product-grid-item product type-product post-3764 status-publish last instock product_cat-home-fragrance product_cat-special-offers has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"11\" data-id=\"3764\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/ivyfragrance.com\/ar\/product\/summer-vibes\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Summer Vibes\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-04-22-at-9.47.22-PM-1024x1024.jpeg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-04-22-at-9.47.22-PM-1024x1024.jpeg 1024w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-04-22-at-9.47.22-PM-300x300.jpeg 300w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-04-22-at-9.47.22-PM-150x150.jpeg 150w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-04-22-at-9.47.22-PM-768x768.jpeg 768w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-04-22-at-9.47.22-PM-12x12.jpeg 12w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-04-22-at-9.47.22-PM-800x800.jpeg 800w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-04-22-at-9.47.22-PM-400x400.jpeg 400w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-04-22-at-9.47.22-PM-600x600.jpeg 600w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-04-22-at-9.47.22-PM.jpeg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"\/ar\/wp-json\/wp\/v2\/pages\/5?add-to-cart=3764\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_3764\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"3764\" data-product_sku=\"IVY-1013\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Summer Vibes&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Summer Vibes&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0633\u0644\u0629 \u0627\u0644\u0645\u0634\u062a\u0631\u064a\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_3764\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/ivyfragrance.com\/ar\/product\/summer-vibes\/\">Summer Vibes<\/a><\/h3>\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x639;.<\/span>&nbsp;12.00<\/bdi><\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-icons product-grid-item product type-product post-48 status-publish first outofstock product_cat-home-fragrance product_cat-special-offers has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"12\" data-id=\"48\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/ivyfragrance.com\/ar\/product\/touch-of-oud\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"\u062a\u0634 \u0627\u0648\u0641 \u0639\u0648\u062f\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"out-of-stock product-label\">Sold out<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/676b1a9c-9e67-47cc-9303-b1fd4d1e320b-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/676b1a9c-9e67-47cc-9303-b1fd4d1e320b-1024x1024.jpg 1024w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/676b1a9c-9e67-47cc-9303-b1fd4d1e320b-300x300.jpg 300w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/676b1a9c-9e67-47cc-9303-b1fd4d1e320b-150x150.jpg 150w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/676b1a9c-9e67-47cc-9303-b1fd4d1e320b-768x768.jpg 768w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/676b1a9c-9e67-47cc-9303-b1fd4d1e320b-12x12.jpg 12w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/676b1a9c-9e67-47cc-9303-b1fd4d1e320b-800x800.jpg 800w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/676b1a9c-9e67-47cc-9303-b1fd4d1e320b-400x400.jpg 400w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/676b1a9c-9e67-47cc-9303-b1fd4d1e320b-600x600.jpg 600w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/676b1a9c-9e67-47cc-9303-b1fd4d1e320b.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/8d7caff0-cd68-4430-8af5-49cb88eef885-819x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/8d7caff0-cd68-4430-8af5-49cb88eef885-819x1024.jpg 819w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/8d7caff0-cd68-4430-8af5-49cb88eef885-240x300.jpg 240w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/8d7caff0-cd68-4430-8af5-49cb88eef885-768x960.jpg 768w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/8d7caff0-cd68-4430-8af5-49cb88eef885-1229x1536.jpg 1229w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/8d7caff0-cd68-4430-8af5-49cb88eef885-10x12.jpg 10w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/8d7caff0-cd68-4430-8af5-49cb88eef885-800x1000.jpg 800w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/8d7caff0-cd68-4430-8af5-49cb88eef885-400x500.jpg 400w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/8d7caff0-cd68-4430-8af5-49cb88eef885-600x750.jpg 600w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/8d7caff0-cd68-4430-8af5-49cb88eef885-150x188.jpg 150w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2022\/11\/8d7caff0-cd68-4430-8af5-49cb88eef885.jpg 1280w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/ivyfragrance.com\/ar\/product\/touch-of-oud\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_48\" data-quantity=\"1\" class=\"button product_type_simple add-to-cart-loop\" data-product_id=\"48\" data-product_sku=\"IVY-1004\" aria-label=\"\u0625\u0642\u0631\u0623 \u0627\u0644\u0645\u0632\u064a\u062f \u0639\u0646 \u201cTouch of Oud\u201d\" rel=\"nofollow\" data-success_message=\"\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u0632\u064a\u062f<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_48\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/ivyfragrance.com\/ar\/product\/touch-of-oud\/\">\u062a\u0634 \u0627\u0648\u0641 \u0639\u0648\u062f<\/a><\/h3>\t\t\t\t\t\t\t\t\t\n\t\t\t\t<div class=\"star-rating\" role=\"img\" aria-label=\"\u062a\u0645 \u0627\u0644\u062a\u0642\u064a\u064a\u0645 5.00 \u0645\u0646 5\" data-no-translation-aria-label=\"\">\n\t\t\t\t\t<span style=\"width:100%\">\n\t\t\t\u062a\u0645 \u0627\u0644\u062a\u0642\u064a\u064a\u0645 <strong class=\"rating\">5.00<\/strong> \u0645\u0646 5\t\t<\/span>\n\t\t\t\t<\/div>\n\n\t\t\n\t\t\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#x631;.&#x639;.<\/span>&nbsp;12.00<\/bdi><\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"wd-nav-arrows wd-pos-sep wd-hover-1 wd-icon-1\">\n\t\t\t<div class=\"wd-btn-arrow wd-prev wd-disabled\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"wd-btn-arrow wd-next\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-eccc946 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"eccc946\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-acfbd7d\" data-id=\"acfbd7d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f3c3f2a elementor-widget elementor-widget-spacer\" data-id=\"f3c3f2a\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-b2d645e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b2d645e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5c90d83\" data-id=\"5c90d83\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4990c53 elementor-widget elementor-widget-heading\" data-id=\"4990c53\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">\u0622\u0631\u0627\u0621 \u0627\u0644\u0632\u0628\u0627\u0626\u0646<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-ef424df elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ef424df\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-10be4c1\" data-id=\"10be4c1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1618411 elementor-widget elementor-widget-spacer\" data-id=\"1618411\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-257c820 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"257c820\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8f6e685\" data-id=\"8f6e685\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-1a4dd94 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1a4dd94\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5474c8b\" data-id=\"5474c8b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d0d33bb animated-slow elementor-invisible elementor-widget elementor-widget-image\" data-id=\"d0d33bb\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInDown&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"780\" src=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/06\/IMG_1713.png\" class=\"attachment-full size-full wp-image-4699\" alt=\"\" srcset=\"https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/06\/IMG_1713.png 1920w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/06\/IMG_1713-300x122.png 300w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/06\/IMG_1713-1024x416.png 1024w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/06\/IMG_1713-768x312.png 768w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/06\/IMG_1713-1536x624.png 1536w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/06\/IMG_1713-18x7.png 18w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/06\/IMG_1713-400x163.png 400w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/06\/IMG_1713-600x244.png 600w, https:\/\/ivyfragrance.com\/wp-content\/uploads\/2026\/06\/IMG_1713-150x61.png 150w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-b069b72 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b069b72\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-98992f9\" data-id=\"98992f9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b94047b elementor-widget elementor-widget-heading\" data-id=\"b94047b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0622\u064a\u0641\u064a \u0647\u0648 \u0623\u0643\u062b\u0631 \u0645\u0646 \u0645\u062c\u0631\u062f \u0639\u0637\u0631<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>New Arrival -10% Add to cart Blush Rose &#x631;.&#x639;.&nbsp;19.00 Original price was: &#x631;.&#x639;.&nbsp;19.00.&#x631;.&#x639;.&nbsp;17.10Current price is: &#x631;.&#x639;.&nbsp;17.10. Add to cart Hakman<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-5","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/ivyfragrance.com\/ar\/wp-json\/wp\/v2\/pages\/5","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ivyfragrance.com\/ar\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ivyfragrance.com\/ar\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ivyfragrance.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ivyfragrance.com\/ar\/wp-json\/wp\/v2\/comments?post=5"}],"version-history":[{"count":515,"href":"https:\/\/ivyfragrance.com\/ar\/wp-json\/wp\/v2\/pages\/5\/revisions"}],"predecessor-version":[{"id":4703,"href":"https:\/\/ivyfragrance.com\/ar\/wp-json\/wp\/v2\/pages\/5\/revisions\/4703"}],"wp:attachment":[{"href":"https:\/\/ivyfragrance.com\/ar\/wp-json\/wp\/v2\/media?parent=5"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}